{"id":14475,"date":"2026-02-26T04:37:04","date_gmt":"2026-02-26T03:37:04","guid":{"rendered":"https:\/\/rowermax.shop\/ro64\/produkt\/lekki-rower-dla-dziecka-woom-go-3-automagic-16-hot-pink-rozowy-malionowy\/"},"modified":"2026-02-26T04:37:05","modified_gmt":"2026-02-26T03:37:05","slug":"lekki-rower-dla-dziecka-woom-go-3-automagic-16-hot-pink-rozowy-malionowy","status":"publish","type":"product","link":"https:\/\/velxori.shop\/ro64\/produkt\/lekki-rower-dla-dziecka-woom-go-3-automagic-16-hot-pink-rozowy-malionowy\/","title":{"rendered":"Lekki Rower dla dziecka Woom GO 3 Automagic 16&quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">woom GO 3 AUTOMAGIC<\/h3>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Superlekki rowerek na k\u00f3\u0142kach 16&#8243; dla ma\u0142ych dzieciak\u00f3w, kt\u00f3re jeszcze nie potrafi\u0105 obs\u0142ugiwa\u0107 przerzutek, ale chc\u0105 bezpiecznie je\u017adzi\u0107 dalej i szybciej. &nbsp;Optymalny od czterech lat wzwy\u017c.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>Rower:&nbsp;<\/b>16\u2033&nbsp;&nbsp;\u2022&nbsp;&nbsp;6,2 kg<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>Dziecko:&nbsp;<\/b>4 &#8211; 6 lat&nbsp;&nbsp;\u2022&nbsp;&nbsp;105 &#8211; 120 cm<\/p>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">woom GO 3 AUTOMAGIC<\/h3>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Magia pr\u0119dko\u015bci<\/h3>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Czy Twoje dziecko zawsze jest w ruchu, ciesz\u0105c si\u0119 \u017cyciem na rowerze?&nbsp;woom&nbsp;GO 3 AUTOMAGIC stworzono z my\u015bl\u0105 o m\u0142odocianych pasjonatach! Ten wyj\u0105tkowy rower ma dwa biegi, ale Twoje dziecko nie musi martwi\u0107 si\u0119 o ich zmian\u0119. Automatyczna przek\u0142adnia pia\u015bcie poradzi sobie z tym&#8230; automatycznie. Jazda pod g\u00f3rk\u0119 b\u0119dzie \u0142atwiejsza, a na p\u0142askim rower pozwoli szybciej jecha\u0107, bez kr\u0119cenia jak chomiczek. To magia. A w zasadzie AUTOMAGIC!<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\"><b>Najwa\u017cniejsze cechy:<\/b>&nbsp;Automatyczna, dwubiegowa przek\u0142adnia o szerokim zakresie prze\u0142o\u017ce\u0144, tylny hamulec oznaczony na zielono, stabilizator kierownicy, ergonomiczne siode\u0142ko, uchwyty dopasowane do wielko\u015bci d\u0142oni dziecka i zako\u0144czone pier\u015bcieniami bezpiecze\u0144stwa, a wszystko to wyprodukowane bez toksycznych substancji. Kierownica w stylu BMX i os\u0142ona \u0142a\u0144cucha dope\u0142niaj\u0105 ca\u0142o\u015bci.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rozmiar:&nbsp;<b>16\u2033<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Waga:&nbsp;<b>6,2 kg (bez peda\u0142\u00f3w)<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wiek:&nbsp;<b>4 &#8211; 6<\/b>&nbsp;lat<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wzrost:&nbsp;<b>105 &#8211; 120<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Dost\u0119pne edycje:&nbsp;<b>GO<\/b><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy\" srcset=\"https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 360w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 720w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1024w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1440w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h2>woom GO 3 AUTOMAGIC<\/h2>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Specyfikacja<\/h3>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Rama<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekka, wysokiej jako\u015bci rama wykonana z aluminium AA 6061<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ko\u0142a 16\u2033<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">\u0141atwo\u015b\u0107 prowadzenia: niski przekrok, bardzo niska pozycja jad\u0105cego dziecka, d\u0142ugi rozstaw osi i samosteruj\u0105ca geometria przedniego ko\u0142a zapewniaj\u0105 du\u017c\u0105 stabilno\u015b\u0107, dobry balans i wi\u0119cej rado\u015bci dla jad\u0105cego, a tak\u017ce spokoju g\u0142owy dla obserwuj\u0105cych popisy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Ko\u0142a<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultralekkie aluminiowe obr\u0119cze<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Prz\u00f3d: ultralekka piasta z uszczelnianymi \u0142o\u017cyskami<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Monta\u017c i demonta\u017c za pomoc\u0105 klucza imbusowego 5 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ty\u0142: Piasta Sturmey-Archer Automatic A2 z uszczelnianymi \u0142o\u017cyskami<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Monta\u017c i demonta\u017c za pomoc\u0105 klucza 15 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">16 lekkich, super mocnych stalowych szprych, zaplecionych na krzy\u017c<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Widelec<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekki aluminiowy widelec typu unicrown<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Rura sterowa 1\u2033<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ustawienie widelca wzgl\u0119dem ko\u0142a zapewnia du\u017c\u0105 samosterowno\u015b\u0107, u\u0142atwiaj\u0105c\u0105 bezpieczn\u0105 jazd\u0119<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Opony<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">16 \u00d7 1.4\u2033 Schwalbe Little Joe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wyprodukowane zgodnie z \u201cdoros\u0142ymi\u201d technologiami maj\u0105 jako\u015b\u0107 wymagan\u0105 nawet przez specjalist\u00f3w, a wi\u0119c przy \u015bwietnej przyczepno\u015bci s\u0105 bardzo lekkie i maj\u0105 niskie opory toczenia \u2013 bardzo podnosi to poziom bezpiecze\u0144stwa przy minimalnym wysi\u0142ku<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Samochodowe wentyle umo\u017cliwiaj\u0105ce pompowanie opon nawet na stacjach benzynowych<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Odblaskowe paski zwi\u0119kszaj\u0105 widoczno\u015b\u0107 z boku<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Stery<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W pe\u0142ni zintegrowane stery 1\u2033<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Uszczelnione \u0142o\u017cyska maszynowe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zintegrowana obejma stabilizuj\u0105ca<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Stabilizator kierownicy<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Elastyczny gumowy pier\u015bcie\u0144 \u0142\u0105cz\u0105cy widelec z ram\u0105<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Stabilizuje kierowanie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zapobiega upadkom spowodowanym nadmiernym skr\u0119ceniem kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Mostek<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultralekki mostek z aluminium wzmocnionego kuciem<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">40 mm \/ +15\u00b0<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wpuszczona \u015bruba zaciskowa i zaokr\u0105glony kszta\u0142t \u2013 maksymalnie przyjazny dla kolan<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Kierownica przymocowana do mostka za pomoc\u0105 dw\u00f3ch \u015brub imbusowych 4 mm<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Siode\u0142ko<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczny i dopasowany do wieku u\u017cytkownika design<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wytrzyma\u0142y i odporny na warunki atmosferyczne materia\u0142 wierzchni<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Kierownica<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Szeroka, ergonomiczna i lekka kierownica z aluminium dla lepszej kontroli<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W stylu BMX z wysokim wznosem dla pe\u0142nej adaptacji do wzrostu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Oznaczenie ABC do precyzyjnej regulacji wysoko\u015bci siod\u0142a w stosunku do kierownicy<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Piaskowana i anodowana na czarno, wi\u0119c farba nie odpry\u015bnie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Cienki uchwyt, odpowiedni nawet dla bardzo ma\u0142ych d\u0142oni<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Szeroko\u015b\u0107: 500 mm<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Rura siod\u0142owa<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Anodowana aluminiowa rura siod\u0142owa, wi\u0119c farba nie odpry\u015bnie, z widoczn\u0105 lini\u0105 maksymalnego wysuni\u0119cia<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zintegrowany zestaw redukcyjny w rurze siod\u0142owej, zapobiegaj\u0105cy rysowaniu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Oznaczenie ABC dla \u0142atwej i precyzyjnej regulacji wysoko\u015bci siod\u0142a w stosunku do kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Chwyty<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczny kszta\u0142t<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultra cienki, dostosowany \u015brednic\u0105 do dzieci\u0119cych d\u0142oni uchwyt, zapewniaj\u0105cy pewne trzymanie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Strefa komfortu, zapewniaj\u0105ca idealny kontakt d\u0142oni z kierownic\u0105<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Powi\u0119kszone ko\u0144c\u00f3wki dla ochrony d\u0142oni w razie upadku<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Chwyty typu lock-on, czyli ze skr\u0119can\u0105 \u015brubkami obejm\u0105, uniemo\u017cliwiaj\u0105c\u0105 obracanie si\u0119 nawet na mokrej kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Zacisk rury siod\u0142owej<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wykonany z aluminium szybkozamykacz z d\u0142ug\u0105 d\u017awigni\u0105 u\u0142atwiaj\u0105c\u0105 regulacje przy u\u017cyciu minimalnej si\u0142y<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Eliminuje ryzyko skr\u0119cania i\/lub obracania<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Nap\u0119d<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Bezobs\u0142ugowa dwubiegowa piasta<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekkie, kute aluminiowe korby o d\u0142ugo\u015bci 95 mm z w\u0105skim rozstawem (Q-factor) peda\u0142\u00f3w<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">18 z\u0119b\u00f3w z przodu i 10 z\u0119b\u00f3w z ty\u0142u<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W\u0105skie, dzieci\u0119ce, p\u0142askie plastikowe peda\u0142y platformowe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Uszczelniony wk\u0142ad suportu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Brak hamulca torpedo \u2013 u\u0142atwia dziecku startowanie! Bo zawsze mo\u017ce ustawi\u0107 peda\u0142 w wygodnej do ruszania pozycji<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Hamulce<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Dwa niezale\u017cnie dzia\u0142aj\u0105ce mini V-brake, wymagaj\u0105ce minimalnej si\u0142y, do uzyskania maksymalnej si\u0142y hamowania<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczna klamka hamulca zaprojektowana z my\u015bl\u0105 o ma\u0142ych d\u0142oniach, kr\u00f3tkich palcach i niewielkiej sile<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wysokiej jako\u015bci linki hamulcowe Jagwire o niskim wsp\u00f3\u0142czynniku tarcia, zapewniaj\u0105ce lekkie i p\u0142ynne dzia\u0142anie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zielona klamka hamulca i klocki hamulcowe, dla identyfikacji wizualnej tylnego hamulca<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Do\u0142\u0105czone narz\u0119dzia<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">P\u0142aski klucz 15 mm do peda\u0142\u00f3w<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">4 mm imbus do wspornika kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Kolory<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">woom red, vibrant yellow, hot pink, metallic turquoise, metallic blue<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Waga<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">6,2 kg (bez peda\u0142\u00f3w)<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Limit obci\u0105\u017cenia<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">60 kg<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wszystkie komponenty zaprojektowane ze szczeg\u00f3lnym uwzgl\u0119dnieniem zasad bezpiecze\u0144stwa zosta\u0142y opatrzone znakiem kidsafe PLUS. Kliknij w ikonki na grafice powy\u017cej, aby dowiedzie\u0107 si\u0119 wi\u0119cej na temat bezpiecze\u0144stwa.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy\" srcset=\"https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 360w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 720w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1024w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1440w,https:\/\/a.allegroimg.com\/original\/11adbe\/f7ff439444a58e36590d68136adb\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany\" srcset=\"https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 360w,https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 720w,https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1024w,https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1440w,https:\/\/a.allegroimg.com\/original\/118088\/8a514bfe493c82e295a1cf9a258d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Stopie\u0144 z\u0142o\u017cenia wst\u0119pnie z\u0142o\u017cony, wyregulowany\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic\" srcset=\"https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic 360w,https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic 720w,https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic 1024w,https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic 1440w,https:\/\/a.allegroimg.com\/original\/11301c\/7f4b2e18452f869236af247163db\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kod-producenta-Woom-3-Go-Automagic 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Kod producenta Woom 3 Go Automagic\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom\" srcset=\"https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom 360w,https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom 720w,https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom 1024w,https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom 1440w,https:\/\/a.allegroimg.com\/original\/11110e\/51cee3664ab498812c361b45775c\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Marka-Woom 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Marka Woom\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1357px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC\" srcset=\"https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC 360w,https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC 720w,https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC 1024w,https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC 1440w,https:\/\/a.allegroimg.com\/original\/113e49\/b6857b614841ab237e91f899deb0\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Model-GO-3-AUTOMAGIC 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Model GO 3 AUTOMAGIC\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1279px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks\" srcset=\"https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks 360w,https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks 720w,https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks 1024w,https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks 1440w,https:\/\/a.allegroimg.com\/original\/11d64a\/c3e05bc443f78cff1f5208a936d3\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Plec-produkt-uniseks 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy P\u0142e\u0107 produkt uniseks\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1357px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza\" srcset=\"https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza 360w,https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza 720w,https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza 1024w,https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza 1440w,https:\/\/a.allegroimg.com\/original\/118251\/61e11d5e4804a64b1dc326e89d9d\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Rozmiar-ramy-mniejsza 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Rozmiar ramy mniejsza\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy\" srcset=\"https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy 360w,https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy 720w,https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy 1024w,https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy 1440w,https:\/\/a.allegroimg.com\/original\/1130a0\/3563dcfa46c5ae672e45a5ee051b\/Lekki-Rower-dla-dziecka-Woom-GO-3-Automagic-16-Hot-Pink-Rozowy-Malionowy-Kolor-rozowy 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 3 Automagic 16&amp;quot; Hot Pink\/R\u00f3\u017cowy\/Malionowy Kolor r\u00f3\u017cowy\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>woom GO 3 AUTOMAGIC<\/p>\n<p>Superlekki rowerek na k\u00f3\u0142kach 16&quot; dla ma\u0142ych dzieciak\u00f3w, kt\u00f3re jeszcze nie potrafi\u0105 obs\u0142ugiwa\u0107 przerzutek, ale chc\u0105 bezpiecznie je\u017adzi\u0107 dalej i szybciej. &nbsp;Optymalny od czterech lat wzwy\u017c.<\/p>\n<p>Rower:&nbsp;16\u2033&nbsp;&nbsp;\u2022&nbsp;&nbsp;6,2 kg<\/p>\n<p>Dziecko:&nbsp;4 &#8211; 6 lat&nbsp;&nbsp;\u2022&nbsp;&nbsp;105 &#8211; 120 cm<\/p>\n<p>woom GO 3 AUTOMAGIC<\/p>\n<p>Magia pr\u0119dko\u015bci<\/p>\n","protected":false},"featured_media":14476,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[705],"product_cat":[728,688,730,687],"product_tag":[],"class_list":{"0":"post-14475","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-woom","7":"product_cat-mtb-gorskie","8":"product_cat-rowery","9":"product_cat-rowery-dh","10":"product_cat-rowery-i-akcesoria","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475.jpg",1920,1280,false],"thumbnail":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-150x150.jpg",150,150,true],"medium":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-300x200.jpg",300,200,true],"medium_large":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-768x512.jpg",768,512,true],"large":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475.jpg",1920,1280,false],"woocommerce_thumbnail":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/velxori.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14475-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/velxori.shop\/ro64\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"woom GO 3 AUTOMAGIC Superlekki rowerek na k\u00f3\u0142kach 16&quot; dla ma\u0142ych dzieciak\u00f3w, kt\u00f3re jeszcze nie potrafi\u0105 obs\u0142ugiwa\u0107 przerzutek, ale chc\u0105 bezpiecznie je\u017adzi\u0107 dalej i szybciej. &nbsp;Optymalny od czterech lat wzwy\u017c. Rower:&nbsp;16\u2033&nbsp;&nbsp;\u2022&nbsp;&nbsp;6,2 kg Dziecko:&nbsp;4 - 6 lat&nbsp;&nbsp;\u2022&nbsp;&nbsp;105 - 120 cm woom GO 3 AUTOMAGIC Magia pr\u0119dko\u015bci","_links":{"self":[{"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/product\/14475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/media\/14476"}],"wp:attachment":[{"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/media?parent=14475"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/product_brand?post=14475"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/product_cat?post=14475"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/velxori.shop\/ro64\/wp-json\/wp\/v2\/product_tag?post=14475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}